{"id":5202,"date":"2024-11-17T21:45:58","date_gmt":"2024-11-17T13:45:58","guid":{"rendered":"https:\/\/vman-sea.com\/uncategorized-th\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/"},"modified":"2025-03-18T15:40:24","modified_gmt":"2025-03-18T07:40:24","slug":"%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/","title":{"rendered":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23: \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e0a\u0e27\u0e19\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e19\u0e27\u0e19\u0e34\u0e22\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e40\u0e25\u0e48\u0e21\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e2d\u0e48\u0e32\u0e19\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e23\u0e32\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e19\u0e35\u0e49  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22: <em>\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e32\u0e27\u0e1c\u0e35<\/em> \u0e42\u0e14\u0e22 Yangsze Choo<\/strong><\/h2>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg\" data-alt=\"The Ghost Bride\" title=\"THE-GHOST-BRIDE\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-GHOST-BRIDE.jpg\" width=\"1600\" height=\"2409\" alt=\"The Ghost Bride\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n                    <div class=\"image-caption__wrapper\">\n\n                        <!-- Automatically use the translated caption -->\n                        <figcaption>Courtesy\u00a0<em><strong>AMANDA&#8217;S BOOK CORNER<\/strong><\/em><\/figcaption>\n\n                    <\/div>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u0e25\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e1b\u0e25\u0e01\u0e46 \u0e08\u0e32\u0e01\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e25\u0e34\u0e21\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e18\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e32\u0e27\u0e1c\u0e35\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e0a\u0e32\u0e22\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a \u0e2b\u0e32\u0e01\u0e40\u0e18\u0e2d\u0e15\u0e01\u0e25\u0e07 \u0e40\u0e18\u0e2d\u0e01\u0e47\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e19\u0e44\u0e1b\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e07\u0e25\u0e34\u0e1a\u0e25\u0e34\u0e48\u0e27 <a href=\"https:\/\/amandasbookcorner.com\/2018\/01\/13\/the-ghost-bride\/\" title=\"\"><em>The<\/em> <em>Ghost<\/em> <em>Bride<\/em><\/a> \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e27\u0e19\u0e34\u0e22\u0e32\u0e22\u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e41\u0e1b\u0e25\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e31\u0e19\u0e21\u0e32\u0e08\u0e19\u0e16\u0e36\u0e07\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e09\u0e32\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e30\u0e25\u0e30\u0e01\u0e32\u0e43\u0e19\u0e22\u0e38\u0e04\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29 1890 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e1b\u0e34\u0e19\u0e2a\u0e4c: <em>\u0e16\u0e49\u0e33\u0e41\u0e25\u0e30\u0e40\u0e07\u0e32<\/em> \u0e42\u0e14\u0e22 Nick Joaquin<\/strong><\/h2>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg\" data-alt=\"Cave and Shadows\" title=\"CAVE-AND-SHADOWS\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/CAVE-AND-SHADOWS.jpg\" width=\"1600\" height=\"2409\" alt=\"Cave and Shadows\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n                    <div class=\"image-caption__wrapper\">\n\n                        <!-- Automatically use the translated caption -->\n                        <figcaption>Courtesy\u00a0<em><strong>PHILIPPINE BOOKS<\/strong><\/em><\/figcaption>\n\n                    <\/div>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u0e28\u0e1e\u0e02\u0e2d\u0e07\u0e40\u0e19\u0e19\u0e34\u0e15\u0e32 \u0e04\u0e39\u0e41\u0e01\u0e19 \u0e16\u0e39\u0e01\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e43\u0e19\u0e16\u0e49\u0e33\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e1b\u0e34\u0e14\u0e15\u0e32\u0e22 \u0e1e\u0e48\u0e2d\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d \u0e41\u0e08\u0e47\u0e01 \u0e40\u0e2e\u0e19\u0e2a\u0e31\u0e19 \u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e35\u0e48\u0e21\u0e30\u0e19\u0e34\u0e25\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e02\u0e04\u0e14\u0e35 <em><a href=\"https:\/\/www.philippinebooks.com\/products\/cave-and-shadows?srsltid=AfmBOorpvRCKedElmEFkHGC2Qf6bgflGc6nvkRJK05WwoezpDzbDvdt0\" title=\"\">Cave and Shadows<\/a><\/em> \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e23\u0e2d\u0e22\u0e41\u0e22\u0e01\u0e2d\u0e31\u0e19\u0e21\u0e37\u0e14\u0e21\u0e34\u0e14 \u0e25\u0e2d\u0e07\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e07\u0e32\u0e21\u0e37\u0e14\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e04\u0e38\u0e13\u0e08\u0e30\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e25\u0e48\u0e21\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e01\u0e32\u0e23\u0e44\u0e02\u0e04\u0e14\u0e35\u0e1b\u0e23\u0e34\u0e28\u0e19\u0e32 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e25\u0e31\u0e17\u0e18\u0e34\u0e25\u0e48\u0e32\u0e2d\u0e32\u0e13\u0e32\u0e19\u0e34\u0e04\u0e21\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e34\u0e04 \u0e42\u0e08\u0e04\u0e27\u0e34\u0e19 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e08\u0e38\u0e14\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e43\u0e19\u0e19\u0e34\u0e01\u0e32\u0e22\u0e42\u0e23\u0e21\u0e31\u0e19\u0e04\u0e32\u0e18\u0e2d\u0e25\u0e34\u0e01\u0e02\u0e2d\u0e07\u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e1b\u0e34\u0e19\u0e2a\u0e4c (\u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e1b\u0e34\u0e19\u0e2a\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e19\u0e31\u0e1a\u0e16\u0e37\u0e2d\u0e19\u0e34\u0e01\u0e32\u0e22\u0e42\u0e23\u0e21\u0e31\u0e19\u0e04\u0e32\u0e18\u0e2d\u0e25\u0e34\u0e01\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22) \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e1a\u0e1a\u0e19\u0e2d\u0e01\u0e23\u0e35\u0e15\u0e43\u0e19\u0e22\u0e38\u0e04\u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e32\u0e13\u0e32\u0e19\u0e34\u0e04\u0e21    <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32: <em>Afterparty<\/em> \u0e42\u0e14\u0e22 Anthony Veasna So<\/strong><\/h2>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg\" data-alt=\"Afterparties book\" title=\"AFTERPARTIES\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/AFTERPARTIES.jpg\" width=\"1600\" height=\"2409\" alt=\"Afterparties book\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n                    <div class=\"image-caption__wrapper\">\n\n                        <!-- Automatically use the translated caption -->\n                        <figcaption>Courtesy\u00a0<em><strong>NPR<\/strong><\/em><\/figcaption>\n\n                    <\/div>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a <a href=\"https:\/\/www.voacambodia.com\/a\/book-by-cambodian-american-author-who-died-on-brink-of-stardom-receives-much-acclaim\/6014147.html\">\u0e0a\u0e32\u0e27\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e32\u0e01\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23<\/a> \u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e40\u0e02\u0e21\u0e23\u0e41\u0e14\u0e07 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e30\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e41\u0e15\u0e48\u0e41\u0e2d\u0e19\u0e42\u0e18\u0e19\u0e35 \u0e40\u0e27\u0e2a\u0e19\u0e32 \u0e42\u0e0b \u0e01\u0e31\u0e07\u0e27\u0e25\u0e27\u0e48\u0e32\u0e42\u0e25\u0e01 <a href=\"https:\/\/electricliterature.com\/there-is-more-than-one-way-to-be-cambodian\/\">\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e0a\u0e32\u0e27\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e47\u0e1a\u0e1b\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<\/a> \u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e0a\u0e32\u0e27\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32-\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e17\u0e33\u0e25\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e14\u0e49\u0e27\u0e22 <em>Afterparties<\/em> \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e25\u0e35\u0e49\u0e20\u0e31\u0e22\u0e43\u0e19\u0e41\u0e04\u0e25\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e35\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e20\u0e32\u0e23\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e21\u0e23\u0e41\u0e14\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e1e\u0e28 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c:<\/strong> <strong><em>\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e25\u0e35 \u0e0a\u0e32\u0e19 \u0e2e\u0e47\u0e2d\u0e01 \u0e40\u0e0a<\/em> \u0e42\u0e14\u0e22 \u0e0b\u0e2d\u0e19\u0e19\u0e35\u0e48 \u0e25\u0e34\u0e27<\/strong><\/h2>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg\" data-alt=\"The Art of Charlie Chan Hock Chye\" title=\"THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/THE-ART-OF-CHARLIE-CHAN-HOCK-CHYE.jpg\" width=\"1600\" height=\"2409\" alt=\"The Art of Charlie Chan Hock Chye\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n                    <div class=\"image-caption__wrapper\">\n\n                        <!-- Automatically use the translated caption -->\n                        <figcaption>Courtesy\u00a0<em><strong>GOODREADS<\/strong><\/em><\/figcaption>\n\n                    <\/div>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Sonny Liew \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23: \u0e0a\u0e35\u0e27\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07 Charlie Chan Hock Chye \u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e38\u0e01\u0e40\u0e1a\u0e34\u0e01\u0e41\u0e15\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21\u0e44\u0e1b\u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27 (\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e2a\u0e21\u0e21\u0e15\u0e34) \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e2b\u0e49\u0e32\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29 \"\u0e0a\u0e35\u0e27\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\" \u0e40\u0e25\u0e48\u0e21\u0e19\u0e35\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e27\u0e19\u0e34\u0e22\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e32\u0e15\u0e34 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e02\u0e2d\u0e07 Liew \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c\u0e41\u0e21\u0e49\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e38\u0e14\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e19\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2d\u0e48\u0e2d\u0e19\u0e0b\u0e36\u0e48\u0e07 \"\u0e2d\u0e32\u0e08\u0e1a\u0e31\u0e48\u0e19\u0e17\u0e2d\u0e19\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\" \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e25\u0e48\u0e21\u0e19\u0e35\u0e49\u0e02\u0e32\u0e22\u0e2b\u0e21\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Eisner \u0e08\u0e33\u0e19\u0e27\u0e19\u0e2a\u0e32\u0e21\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 (\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2d\u0e2d\u0e2a\u0e01\u0e32\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19)    <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 : <em>\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27<\/em> \u0e42\u0e14\u0e22 \u0e23\u0e31\u0e10\u0e27\u0e38\u0e12\u0e34 \u0e25\u0e32\u0e20\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c<\/strong><\/h2>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg\" data-alt=\"Sightseeing\" title=\"SIGHTSEEING\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/SIGHTSEEING.jpg\" width=\"1600\" height=\"2409\" alt=\"Sightseeing\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n                    <div class=\"image-caption__wrapper\">\n\n                        <!-- Automatically use the translated caption -->\n                        <figcaption>Courtesy\u00a0<em><strong>KOBO<\/strong><\/em><\/figcaption>\n\n                    <\/div>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19 <em>\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d Sightseeing<\/em> \u0e23\u0e31\u0e10\u0e27\u0e38\u0e12\u0e34 \u0e25\u0e32\u0e20\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e48\u0e27\u0e44\u0e17\u0e22 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e16\u0e19\u0e19\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2b\u0e32\u0e14\u0e17\u0e23\u0e32\u0e22\u0e02\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e49\u0e19\u0e0a\u0e38\u0e14\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e01\u0e08\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e01\u0e15\u0e31\u0e0d\u0e0d\u0e39\u0e01\u0e15\u0e40\u0e27\u0e17\u0e35 \u0e04\u0e27\u0e32\u0e21\u0e09\u0e49\u0e2d\u0e09\u0e25 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e49\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e25\u0e32\u0e20\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e01\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e14\u0e49\u0e27\u0e22\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e15\u0e25\u0e01\u0e02\u0e1a\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e49\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e43\u0e04\u0e23\u0e48  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/strong> : <strong><em>Dumb Luck<\/em> \u0e42\u0e14\u0e22 V\u0169 Tr\u1ecdng Ph\u1ee5ng<\/strong><\/h2>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg\" data-alt=\"Dumb Luck\" title=\"DUMB-LUCK\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-120x181.jpg 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-240x361.jpg 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-320x482.jpg 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-640x964.jpg 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-960x1445.jpg 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1280x1927.jpg 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK.jpg\" width=\"1600\" height=\"2409\" alt=\"Dumb Luck\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n                    <div class=\"image-caption__wrapper\">\n\n                        <!-- Automatically use the translated caption -->\n                        <figcaption>Courtesy <em><strong>G\u00e1c X\u00e9p<\/strong><\/em><\/figcaption>\n\n                    <\/div>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">V\u0169 Tr\u1ecdng Ph\u1ee5ng \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 <a href=\"https:\/\/vinpearl.com\/en\/vietnamese-literature-10-most-popular-classic-books-to-read\">\u0e23\u0e32\u0e0a\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e17\u0e32\u0e07\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a> \u0e41\u0e25\u0e30\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e43\u0e19 <em>Dumb Luck<\/em> \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 Xuan \u0e04\u0e19\u0e1e\u0e40\u0e19\u0e08\u0e23\u0e17\u0e35\u0e48\u0e09\u0e25\u0e32\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e41\u0e2b\u0e25\u0e21\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e49\u0e32\u0e27\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e35\u0e23\u0e1a\u0e38\u0e23\u0e38\u0e29\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e35\u0e2b\u0e25\u0e31\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e22\u0e38\u0e04\u0e2d\u0e32\u0e13\u0e32\u0e19\u0e34\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e40\u0e28\u0e2a\u0e43\u0e19\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 1930 <em>Dumb Luck<\/em> \u0e25\u0e49\u0e2d\u0e40\u0e25\u0e35\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e15\u0e37\u0e49\u0e19\u0e40\u0e02\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e0a\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e01\u0e23\u0e30\u0e0e\u0e38\u0e21\u0e1e\u0e35 \u0e2d\u0e04\u0e15\u0e34\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e01\u0e14\u0e02\u0e35\u0e48\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e25\u0e48\u0e21\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e35\u0e22\u0e19\u0e16\u0e39\u0e01 <a href=\"https:\/\/saigoneer.com\/vietnam-literature\/15820-saigoneer-bookshelf-revisiting-vu-trong-phung-s-dumb-luck\">\u0e2b\u0e49\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 1950 \u0e16\u0e36\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 1980<\/a> \u0e41\u0e15\u0e48\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e19\u0e34\u0e22\u0e32\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22..<\/p>\n","protected":false},"author":8,"featured_media":5116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[190],"tags":[1176,1178,1179,1069],"coauthors":[1104],"class_list":["post-5202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-190","tag-1176","tag-1178","tag-1179","tag-1069"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dayne Aduna\"\/>\n\t<meta name=\"google-site-verification\" content=\"9sEmVT39iIbCpwNX21rMqd023btuUwORxEIHZ6boG70\" \/>\n\t<meta name=\"msvalidate.01\" content=\"3ADFD7977E99135C6276B3B510E26B54\" \/>\n\t<meta name=\"p:domain_verify\" content=\"ddd94e5e18aa32daa2fd6fb7f0d982d6\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"th_TH\" \/>\n\t\t<meta property=\"og:site_name\" content=\"VMAN SEA | The vanguard of men&#039;s fashion destinations\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-17T13:45:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-18T07:40:24+00:00\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dayneaduna8\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Dayne Aduna\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#article\",\"name\":\"\\u0e2a\\u0e33\\u0e23\\u0e27\\u0e08\\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49\\u0e1c\\u0e48\\u0e32\\u0e19\\u0e2b\\u0e19\\u0e31\\u0e07\\u0e2a\\u0e37\\u0e2d\\u0e41\\u0e25\\u0e30\\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e23\\u0e32\\u0e27\",\"headline\":\"\\u0e2a\\u0e33\\u0e23\\u0e27\\u0e08\\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49\\u0e1c\\u0e48\\u0e32\\u0e19\\u0e2b\\u0e19\\u0e31\\u0e07\\u0e2a\\u0e37\\u0e2d\\u0e40\\u0e2b\\u0e25\\u0e48\\u0e32\\u0e19\\u0e35\\u0e49\",\"author\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/dayne-aduna\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/DUMB-LUCK-1.jpg\",\"width\":2048,\"height\":2560},\"datePublished\":\"2024-11-17T21:45:58+08:00\",\"dateModified\":\"2025-03-18T15:40:24+08:00\",\"inLanguage\":\"th\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#webpage\"},\"articleSection\":\"\\u0e28\\u0e34\\u0e25\\u0e1b\\u0e30\\u0e41\\u0e25\\u0e30\\u0e27\\u0e31\\u0e12\\u0e19\\u0e18\\u0e23\\u0e23\\u0e21, \\u0e27\\u0e23\\u0e23\\u0e13\\u0e01\\u0e23\\u0e23\\u0e21, \\u0e2b\\u0e19\\u0e31\\u0e07\\u0e2a\\u0e37\\u0e2d, \\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e23\\u0e32\\u0e27, \\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49, \\u0e44\\u0e21\\u0e48\\u0e08\\u0e33\\u0e40\\u0e1b\\u0e47\\u0e19, koji-arsua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/#listItem\",\"name\":\"\\u0e28\\u0e34\\u0e25\\u0e1b\\u0e30\\u0e41\\u0e25\\u0e30\\u0e27\\u0e31\\u0e12\\u0e19\\u0e18\\u0e23\\u0e23\\u0e21\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/#listItem\",\"position\":2,\"name\":\"\\u0e28\\u0e34\\u0e25\\u0e1b\\u0e30\\u0e41\\u0e25\\u0e30\\u0e27\\u0e31\\u0e12\\u0e19\\u0e18\\u0e23\\u0e23\\u0e21\",\"item\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#listItem\",\"name\":\"\\u0e2a\\u0e33\\u0e23\\u0e27\\u0e08\\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49\\u0e1c\\u0e48\\u0e32\\u0e19\\u0e2b\\u0e19\\u0e31\\u0e07\\u0e2a\\u0e37\\u0e2d\\u0e40\\u0e2b\\u0e25\\u0e48\\u0e32\\u0e19\\u0e35\\u0e49\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#listItem\",\"position\":3,\"name\":\"\\u0e2a\\u0e33\\u0e23\\u0e27\\u0e08\\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49\\u0e1c\\u0e48\\u0e32\\u0e19\\u0e2b\\u0e19\\u0e31\\u0e07\\u0e2a\\u0e37\\u0e2d\\u0e40\\u0e2b\\u0e25\\u0e48\\u0e32\\u0e19\\u0e35\\u0e49\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/#listItem\",\"name\":\"\\u0e28\\u0e34\\u0e25\\u0e1b\\u0e30\\u0e41\\u0e25\\u0e30\\u0e27\\u0e31\\u0e12\\u0e19\\u0e18\\u0e23\\u0e23\\u0e21\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#organization\",\"name\":\"VMAN SEA\",\"description\":\"The vanguard of men's fashion destinations\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/VMAN_SEA_logo_.png\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#organizationLogo\",\"width\":2560,\"height\":1440,\"caption\":\"VMAN SEA logo\"},\"image\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vmansea\",\"https:\\\/\\\/x.com\\\/vmansea\",\"https:\\\/\\\/www.instagram.com\\\/vmansea\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@vmansea\",\"https:\\\/\\\/www.youtube.com\\\/@vmansea\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/dayne-aduna\\\/#author\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/dayne-aduna\\\/\",\"name\":\"Dayne Aduna\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dayneaduna8\",\"https:\\\/\\\/www.instagram.com\\\/dayneaduna\\\/\",\"https:\\\/\\\/ph.linkedin.com\\\/in\\\/dayne-aduna-979708210\"],\"description\":\"Dayne Aduna is an Associate Editor at VMAN Southeast Asia, specializing in fashion, grooming, film, television, and contemporary pop culture. With a strong editorial focus on menswear, his work explores how style intersects with shifting cultural movements across Southeast Asia and beyond. His expertise spans fashion journalism, celebrity profiling, grooming and skincare trends, fragrance, runway reporting, and cultural commentary, with a particular eye for emerging creatives and youth-driven style. Dayne has written extensively on fashion houses, seasonal trends, designer collections, and the evolving image of the modern Southeast Asian man, bringing both editorial depth and cultural relevance to his coverage.\",\"jobTitle\":\"Associate Editor\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_9475-1.jpg\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#webpage\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/\",\"name\":\"\\u0e2a\\u0e33\\u0e23\\u0e27\\u0e08\\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49\\u0e1c\\u0e48\\u0e32\\u0e19\\u0e2b\\u0e19\\u0e31\\u0e07\\u0e2a\\u0e37\\u0e2d\\u0e41\\u0e25\\u0e30\\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e23\\u0e32\\u0e27\",\"description\":\"\\u0e27\\u0e23\\u0e23\\u0e13\\u0e01\\u0e23\\u0e23\\u0e21\\u0e02\\u0e2d\\u0e07\\u0e40\\u0e2d\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e15\\u0e30\\u0e27\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e01\\u0e40\\u0e09\\u0e35\\u0e22\\u0e07\\u0e43\\u0e15\\u0e49\\u0e21\\u0e35\\u0e04\\u0e27\\u0e32\\u0e21\\u0e2b\\u0e25\\u0e32\\u0e01\\u0e2b\\u0e25\\u0e32\\u0e22\\u0e40\\u0e0a\\u0e48\\u0e19\\u0e40\\u0e14\\u0e35\\u0e22\\u0e27\\u0e01\\u0e31\\u0e1a\\u0e2d\\u0e32\\u0e2b\\u0e32\\u0e23 \\u0e21\\u0e35\\u0e17\\u0e31\\u0e49\\u0e07\\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e23\\u0e32\\u0e27\\u0e17\\u0e32\\u0e07\\u0e1b\\u0e23\\u0e30\\u0e27\\u0e31\\u0e15\\u0e34\\u0e28\\u0e32\\u0e2a\\u0e15\\u0e23\\u0e4c\\u0e17\\u0e35\\u0e48\\u0e19\\u0e33\\u0e21\\u0e32\\u0e15\\u0e35\\u0e04\\u0e27\\u0e32\\u0e21\\u0e43\\u0e2b\\u0e21\\u0e48 \\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e2a\\u0e22\\u0e2d\\u0e07\\u0e02\\u0e27\\u0e31\\u0e0d \\u0e40\\u0e2a\\u0e35\\u0e22\\u0e14\\u0e2a\\u0e35\\u0e41\\u0e2a\\u0e1a\\u0e2a\\u0e31\\u0e19 \\u0e41\\u0e25\\u0e30\\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e25\\u0e36\\u0e01\\u0e25\\u0e31\\u0e1a\\u0e17\\u0e35\\u0e48\\u0e19\\u0e48\\u0e32\\u0e2a\\u0e19\\u0e43\\u0e08\",\"inLanguage\":\"th\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/dayne-aduna\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/dayne-aduna\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/DUMB-LUCK-1.jpg\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#mainImage\",\"width\":2048,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\\\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\\\/#mainImage\"},\"datePublished\":\"2024-11-17T21:45:58+08:00\",\"dateModified\":\"2025-03-18T15:40:24+08:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/\",\"name\":\"VMAN SEA\",\"description\":\"The vanguard of men's fashion destinations\",\"inLanguage\":\"th\",\"publisher\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27<\/title>\n\n","aioseo_head_json":{"title":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27","description":"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08","canonical_url":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"9sEmVT39iIbCpwNX21rMqd023btuUwORxEIHZ6boG70","msvalidate.01":"3ADFD7977E99135C6276B3B510E26B54","p:domain_verify":"ddd94e5e18aa32daa2fd6fb7f0d982d6","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#article","name":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27","headline":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49","author":{"@id":"https:\/\/vman-sea.com\/th\/author\/dayne-aduna\/#author"},"publisher":{"@id":"https:\/\/vman-sea.com\/th\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg","width":2048,"height":2560},"datePublished":"2024-11-17T21:45:58+08:00","dateModified":"2025-03-18T15:40:24+08:00","inLanguage":"th","mainEntityOfPage":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#webpage"},"isPartOf":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#webpage"},"articleSection":"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21, \u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21, \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27, \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49, \u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19, koji-arsua"},{"@type":"BreadcrumbList","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/#listItem","position":1,"name":"Home","item":"https:\/\/vman-sea.com\/th\/","nextItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/#listItem","name":"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21"}},{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/#listItem","position":2,"name":"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","item":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/","nextItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#listItem","name":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49"},"previousItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#listItem","position":3,"name":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49","previousItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/#listItem","name":"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21"}}]},{"@type":"Organization","@id":"https:\/\/vman-sea.com\/th\/#organization","name":"VMAN SEA","description":"The vanguard of men's fashion destinations","url":"https:\/\/vman-sea.com\/th\/","logo":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/VMAN_SEA_logo_.png","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#organizationLogo","width":2560,"height":1440,"caption":"VMAN SEA logo"},"image":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/vmansea","https:\/\/x.com\/vmansea","https:\/\/www.instagram.com\/vmansea\/","https:\/\/www.tiktok.com\/@vmansea","https:\/\/www.youtube.com\/@vmansea"]},{"@type":"Person","@id":"https:\/\/vman-sea.com\/th\/author\/dayne-aduna\/#author","url":"https:\/\/vman-sea.com\/th\/author\/dayne-aduna\/","name":"Dayne Aduna","sameAs":["https:\/\/www.facebook.com\/dayneaduna8","https:\/\/www.instagram.com\/dayneaduna\/","https:\/\/ph.linkedin.com\/in\/dayne-aduna-979708210"],"description":"Dayne Aduna is an Associate Editor at VMAN Southeast Asia, specializing in fashion, grooming, film, television, and contemporary pop culture. With a strong editorial focus on menswear, his work explores how style intersects with shifting cultural movements across Southeast Asia and beyond. His expertise spans fashion journalism, celebrity profiling, grooming and skincare trends, fragrance, runway reporting, and cultural commentary, with a particular eye for emerging creatives and youth-driven style. Dayne has written extensively on fashion houses, seasonal trends, designer collections, and the evolving image of the modern Southeast Asian man, bringing both editorial depth and cultural relevance to his coverage.","jobTitle":"Associate Editor","image":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2026\/06\/IMG_9475-1.jpg"}},{"@type":"WebPage","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#webpage","url":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/","name":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27","description":"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08","inLanguage":"th","isPartOf":{"@id":"https:\/\/vman-sea.com\/th\/#website"},"breadcrumb":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#breadcrumblist"},"author":{"@id":"https:\/\/vman-sea.com\/th\/author\/dayne-aduna\/#author"},"creator":{"@id":"https:\/\/vman-sea.com\/th\/author\/dayne-aduna\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#mainImage","width":2048,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/#mainImage"},"datePublished":"2024-11-17T21:45:58+08:00","dateModified":"2025-03-18T15:40:24+08:00"},{"@type":"WebSite","@id":"https:\/\/vman-sea.com\/th\/#website","url":"https:\/\/vman-sea.com\/th\/","name":"VMAN SEA","description":"The vanguard of men's fashion destinations","inLanguage":"th","publisher":{"@id":"https:\/\/vman-sea.com\/th\/#organization"}}]},"og:locale":"th_TH","og:site_name":"VMAN SEA | The vanguard of men's fashion destinations","og:type":"article","og:title":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27","og:description":"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08","og:url":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/","og:image":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png","og:image:secure_url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png","og:image:width":1200,"og:image:height":628,"article:published_time":"2024-11-17T13:45:58+00:00","article:modified_time":"2025-03-18T07:40:24+00:00","article:author":"https:\/\/www.facebook.com\/dayneaduna8","twitter:card":"summary_large_image","twitter:title":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27","twitter:description":"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08","twitter:image":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png","twitter:label1":"Written by","twitter:data1":"Dayne Aduna"},"aioseo_meta_data":{"post_id":"5202","title":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27","description":"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e22\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e40\u0e2a\u0e35\u0e22\u0e14\u0e2a\u0e35\u0e41\u0e2a\u0e1a\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08","keywords":null,"keyphrases":{"focus":{"keyphrase":"literature","score":73,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Southeast Asia","score":75,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},{"keyphrase":"books","score":58,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_url":"https:\/\/vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png","og_image_width":"1200","og_image_height":"628","og_image_custom_url":"https:\/\/vman-sea.com\/wp-content\/uploads\/2024\/11\/vman-sea-books.png","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-17 06:40:56","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-11-14 10:03:08","updated":"2026-07-15 19:47:39"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/vman-sea.com\/th\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/vman-sea.com\/th\/category\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/\" title=\"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\">\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/vman-sea.com\/th\/"},{"label":"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","link":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/"},{"label":"\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49","link":"https:\/\/vman-sea.com\/th\/%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%b0%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%95%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%89%e0%b8%b5\/"}],"uagb_featured_image_src":{"full":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",2048,2560,false],"thumbnail":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",77,96,false],"medium":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",2048,2560,false],"medium_large":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",640,800,false],"large":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",2048,2560,false],"1536x1536":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",1229,1536,false],"2048x2048":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",1638,2048,false],"120w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-120x120.jpg",120,120,true],"240w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-240x240.jpg",240,240,true],"320w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-320x320.jpg",320,320,true],"640w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-640x640.jpg",640,640,true],"960w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-960x960.jpg",960,960,true],"1280w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-1280x1280.jpg",1280,1280,true],"1600w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-1600x1600.jpg",1600,1600,true],"1920w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-1920x1920.jpg",1920,1920,true],"2240w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-2048x2240.jpg",2048,2240,true],"2560w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",2048,2560,false],"120w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-120x150.jpg",120,150,true],"240w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-240x300.jpg",240,300,true],"320w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-320x400.jpg",320,400,true],"640w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-640x800.jpg",640,800,true],"960w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-960x1200.jpg",960,1200,true],"1280w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-1280x1600.jpg",1280,1600,true],"1600w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-1600x2000.jpg",1600,2000,true],"1920w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1-1920x2400.jpg",1920,2400,true],"2240w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",2048,2560,false],"2560w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/DUMB-LUCK-1.jpg",2048,2560,false]},"uagb_author_info":{"display_name":"Dayne Aduna","author_link":"https:\/\/vman-sea.com\/th\/author\/dayne-aduna\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22&hellip;","_links":{"self":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/posts\/5202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/comments?post=5202"}],"version-history":[{"count":0,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/posts\/5202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/media\/5116"}],"wp:attachment":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/media?parent=5202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/categories?post=5202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/tags?post=5202"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/coauthors?post=5202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}