{"id":26906,"date":"2025-07-07T18:53:55","date_gmt":"2025-07-07T10:53:55","guid":{"rendered":"https:\/\/vman-sea.com\/uncategorized-th\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/"},"modified":"2026-03-27T22:58:44","modified_gmt":"2026-03-27T14:58:44","slug":"%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e","status":"publish","type":"post","link":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/","title":{"rendered":"\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 Cole Micek \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u0e17\u0e38\u0e01\u0e01\u0e49\u0e32\u0e27\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22<\/h2>\n\n<p class=\"wp-block-paragraph\">\u201c\u0e1c\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19 \u0e41\u0e15\u0e48\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e04\u0e07\u0e14\u0e39\u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e22\u0e32\u0e27\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e40\u0e2d\u0e07\u201d \u0e42\u0e04\u0e25 \u0e21\u0e34\u0e40\u0e0b\u0e01 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e34\u0e14\u0e15\u0e25\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e0a\u0e21\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 <em>VMAN<\/em> Vanity \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01 13 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e34\u0e08\u0e27\u0e31\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32  <\/p>\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e27\u0e48\u0e32\u0e19\u0e32\u0e22\u0e41\u0e1a\u0e1a \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e08\u0e32\u0e01\u0e25\u0e2d\u0e2a\u0e41\u0e2d\u0e07\u0e40\u0e08\u0e25\u0e34\u0e2a\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e23\u0e07\u0e01\u0e32\u0e22\u0e21\u0e32\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2b\u0e32\u0e01\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e19\u0e1a\u0e32\u0e2a\u0e40\u0e01\u0e47\u0e15\u0e1a\u0e2d\u0e25\u0e43\u0e19\u0e25\u0e35\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e40\u0e02\u0e32\u0e01\u0e47\u0e04\u0e07\u0e40\u0e14\u0e34\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e19\u0e34\u0e27\u0e22\u0e2d\u0e23\u0e4c\u0e01\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e21\u0e30\u0e19\u0e34\u0e25\u0e32\u0e41\u0e25\u0e30\u0e44\u0e01\u0e25\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e2d\u0e35\u0e01 <\/p>\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e32\u0e23\u0e32\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e38\u0e48\u0e07\u0e27\u0e38\u0e48\u0e19\u0e27\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e42\u0e04\u0e25\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e31\u0e19: <\/p>\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DLrwFcPzO_g\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\"background:#FFF;border:0;border-radius:3px;margin: 1px;max-width:540px;min-width:326px;padding:0;width:99.375%;width:-webkit-calc(100% - 2px);width:calc(100% - 2px)\"><div style=\"padding:16px\"> <a href=\"https:\/\/www.instagram.com\/reel\/DLrwFcPzO_g\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"background:#FFFFFF;line-height:0;padding:0 0;text-align:center;text-decoration:none;width:100%\" target=\"_blank\"> <div style=\"flex-direction: row;align-items: center\"> <div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 40px;margin-right: 14px;width: 40px\"><\/div> <div style=\"flex-direction: column;flex-grow: 1;justify-content: center\"> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 100px\"><\/div> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 60px\"><\/div><\/div><\/div><div style=\"padding: 19% 0\"><\/div> <div style=\"height:50px;margin:0 auto 12px;width:50px\"><\/div><div style=\"padding-top: 8px\"> <div style=\"color:#3897f0;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:550;line-height:18px\">\u0e14\u0e39\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e19\u0e35\u0e49\u0e1a\u0e19 Instagram<\/div><\/div><div style=\"padding: 12.5% 0\"><\/div> <div style=\"flex-direction: row;margin-bottom: 14px;align-items: center\"><div> <div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div> <div style=\"background-color: #F4F4F4;height: 12.5px;width: 12.5px;flex-grow: 0;margin-right: 14px;margin-left: 2px\"><\/div> <div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div><\/div><div style=\"margin-left: 8px\"> <div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 20px;width: 20px\"><\/div> <div style=\"width: 0;height: 0;border-top: 2px solid transparent;border-left: 6px solid #f4f4f4;border-bottom: 2px solid transparent\"><\/div><\/div><div style=\"margin-left: auto\"> <div style=\"width: 0px;border-top: 8px solid #F4F4F4;border-right: 8px solid transparent\"><\/div> <div style=\"background-color: #F4F4F4;flex-grow: 0;height: 12px;width: 16px\"><\/div> <div style=\"width: 0;height: 0;border-top: 8px solid #F4F4F4;border-left: 8px solid transparent\"><\/div><\/div><\/div> <div style=\"flex-direction: column;flex-grow: 1;justify-content: center;margin-bottom: 24px\"> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 224px\"><\/div> <div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 144px\"><\/div><\/div><\/a><p style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;line-height:17px;margin-bottom:0;margin-top:8px;overflow:hidden;padding:8px 0 7px;text-align:center;white-space:nowrap\"><a href=\"https:\/\/www.instagram.com\/reel\/DLrwFcPzO_g\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:normal;line-height:17px;text-decoration:none\" target=\"_blank\">\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e0a\u0e23\u0e4c\u0e42\u0e14\u0e22 VMAN Southeast Asia (@vmansea)<\/a><\/p><\/div><\/blockquote>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 '\u0e1e\u0e34\u0e40\u0e28\u0e29&#8217;<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e04\u0e25\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e34\u0e08\u0e27\u0e31\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e22\u0e31\u0e07\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22  <\/p>\n\n<p class=\"wp-block-paragraph\">\u201c\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e21\u201d \u0e42\u0e04\u0e25\u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 <a href=\"https:\/\/www.tower28beauty.com\/products\/sos-daily-facial-rescue-spray?srsltid=AfmBOopGAtKdJtkEoXYyCigeDkaxDmJqh6PqQ4oZe5AU450f1_DqrZHD&amp;view=sos-full-size-image-test\" title=\"\">\u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c SOS Rescue \u0e08\u0e32\u0e01 Tower 28<\/a> \u201c\u0e16\u0e49\u0e32\u0e1c\u0e21\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e14\u0e49\u0e04\u0e23\u0e1a\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u201d \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e09\u0e35\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e23\u0e2d\u0e22\u0e41\u0e14\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e30\u0e04\u0e32\u0e22\u0e40\u0e04\u0e37\u0e2d\u0e07 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e25\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 \u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e08\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32    <\/p>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp\" data-alt=\"COLE MICEK\" title=\"VMAN 03 COLE -07\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1920x2400.webp 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-07.webp\" width=\"2048\" height=\"2560\" alt=\"COLE MICEK\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 <a href=\"https:\/\/naturium.com\/products\/dew-glow-moisturizer-spf-50?srsltid=AfmBOorKmR8yfSFmdSy8T-zk7NrXbMW8NJgqRaa0PORbOILN4yDLPBve\" title=\"\">Dew-Glow Moisturizer SPF 50 \u0e08\u0e32\u0e01 Naturium<\/a> \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e35\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u201c\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e21\u0e35\u0e2a\u0e35\u0e41\u0e17\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e09\u0e31\u0e19\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u201d <\/p>\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e42\u0e04\u0e25\u0e08\u0e30\u0e21\u0e35 <a href=\"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/13-%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%ab%e0%b8%ad%e0%b8%a1%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%9a%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b8%ad%e0%b8%81%e0%b8%a7%e0%b9%88%e0%b8%b2-%e0%b8%84%e0%b8%b8\/\" title=\"\">\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21<\/a> \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e15\u0e31\u0e27\u0e08\u0e32\u0e01 Le Labo \u0e41\u0e15\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c <a href=\"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/5-%e0%b8%aa%e0%b8%b8%e0%b8%94%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%a3%e0%b8%b0%e0%b8%87%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%a5\/\" title=\"\">\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e01\u0e25\u0e34\u0e48\u0e19\u0e01\u0e32\u0e22<\/a> \u0e08\u0e32\u0e01 Salt and Stone \u0e01\u0e47\u0e21\u0e35\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e44\u0e14\u0e49  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">\u0e25\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e42\u0e04\u0e25\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e49\u0e27\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e23\u0e39\u0e49\u0e14\u0e35\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e02\u0e32\u0e17\u0e32 <a href=\"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/5-%e0%b9%80%e0%b8%8b%e0%b8%a3%e0%b8%b1%e0%b9%88%e0%b8%a1%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%a7%e0%b8%b1%e0%b8%95%e0%b8%a3%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%94%e0%b8%b9%e0%b9%81\/\" title=\"\">\u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21<\/a> \u0e41\u0e25\u0e30\u0e04\u0e23\u0e35\u0e21\u0e43\u0e19\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e25\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22   <\/p>\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e04\u0e25\u0e22\u0e31\u0e07\u0e43\u0e0a\u0e49\u0e19\u0e34\u0e49\u0e27\u0e19\u0e32\u0e07\u0e41\u0e15\u0e30 <a href=\"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%84%e0%b8%a5%e0%b9%89%e0%b8%b3%e0%b9%83%e0%b8%95%e0%b9%89%e0%b8%95%e0%b8%b2%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3-%e0%b8%ad%e0%b8%b2%e0%b8%a2\/\" title=\"\">\u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e2d\u0e1a<\/a> \u0e14\u0e27\u0e07\u0e15\u0e32\u0e27\u0e31\u0e19\u0e25\u0e30\u0e2a\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e21\u0e35\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e14\u0e35\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e1c\u0e34\u0e27\u0e43\u0e15\u0e49\u0e15\u0e32\u0e08\u0e30\u0e1a\u0e32\u0e07\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e02\u0e2d\u0e07\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e49\u0e27\u0e19\u0e32\u0e07\u0e08\u0e30\u0e2d\u0e48\u0e2d\u0e19\u0e41\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e17\u0e35\u0e48\u0e1a\u0e2d\u0e1a\u0e1a\u0e32\u0e07\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e31\u0e49\u0e19\u0e15\u0e36\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22    <\/p>\n\n<div class=\"image-block \">\n\n    <div class=\"image__wrapper\">\n\n        \n            <figure>\n\n\n                <span class=\"lg-item\" data-src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp\" data-alt=\"COLE MICEK\" title=\"VMAN 03 COLE -11\">\n\n                    <picture>\n\n                        <source media=\"(max-width: 575px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1920x2400.webp 1920w\" sizes=\"calc(100vw - 40px)\">\n\n                        <source media=\"(min-width: 1512px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2560w\" sizes=\"728px\">\n\n                        <source media=\"(min-width: 1200px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2560w\" sizes=\"calc(66vw - 100px)\">\n\n                        <source media=\"(min-width: 992px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2240w\" sizes=\"calc(66vw - 60px)\">\n\n                        <source media=\"(min-width: 768px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2560w\" sizes=\"calc(100vw - 222px)\">\n\n                        <source media=\"(min-width: 576px)\" srcset=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-120x150.webp 120w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-240x300.webp 240w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-320x400.webp 320w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-640x800.webp 640w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-960x1200.webp 960w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1280x1600.webp 1280w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1600x2000.webp 1600w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11-1920x2400.webp 1920w, https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp 2240w\" sizes=\"calc(100vw - 60px)\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/06\/VMAN-03-COLE-11.webp\" width=\"2048\" height=\"2560\" alt=\"COLE MICEK\">\n\n                    <\/picture>\n\n                <\/span>\n\n                \n            <\/figure>\n\n        \n    <\/div>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e04\u0e25\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e14\u0e35\u0e27\u0e48\u0e32\u0e04\u0e34\u0e49\u0e27\u0e04\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e14\u0e39\u0e21\u0e35\u0e21\u0e34\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e39\u0e1b\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e40\u0e02\u0e32\u0e08\u0e36\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e08\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21\u0e41\u0e15\u0e48\u0e07\u0e04\u0e34\u0e49\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e34\u0e49\u0e27\u0e40\u0e23\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07   <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e20\u0e32\u0e1e:<\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 <strong>Krisnoff<\/strong><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 <strong><em>\u0e41\u0e1e\u0e17\u0e23\u0e34\u0e04 \u0e44\u0e17<\/em><\/strong><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 <strong><em>\u0e1a\u0e49\u0e2d\u0e07 \u0e1a\u0e49\u0e2d\u0e07 \u0e1a\u0e27\u0e19<\/em><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d:<\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d <strong><em>\u0e40\u0e1a\u0e23\u0e19\u0e17\u0e4c \u0e2e\u0e32\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c<\/em><\/strong><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e41\u0e01\u0e49\u0e44\u0e02 <strong><em>\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e2d\u0e31\u0e19\u0e15\u0e32\u0e25\u0e31\u0e19<\/em><\/strong><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 <strong><em>Lorenz Namalata (Fatbrain Collective)<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e38\u0e01\u0e01\u0e49\u0e32\u0e27\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22 \u201c\u0e1c\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49..<\/p>\n","protected":false},"author":6,"featured_media":26858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[208],"tags":[3360,1819],"coauthors":[239],"class_list":["post-26906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-208","tag-3360","tag-1819"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here&#039;s how he takes care of himself to face the day.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Angelo Dionora\"\/>\n\t<meta name=\"google-site-verification\" content=\"9sEmVT39iIbCpwNX21rMqd023btuUwORxEIHZ6boG70\" \/>\n\t<meta name=\"msvalidate.01\" content=\"3ADFD7977E99135C6276B3B510E26B54\" \/>\n\t<meta name=\"p:domain_verify\" content=\"ddd94e5e18aa32daa2fd6fb7f0d982d6\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"th_TH\" \/>\n\t\t<meta property=\"og:site_name\" content=\"VMAN SEA | The vanguard of men&#039;s fashion destinations\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Why Cole Micek Swears By an Extensive Skincare Routine\" \/>\n\t\t<meta property=\"og:description\" content=\"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here&#039;s how he takes care of himself to face the day.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-07-07T10:53:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-27T14:58:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Why Cole Micek Swears By an Extensive Skincare Routine\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here&#039;s how he takes care of himself to face the day.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Angelo Dionora\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#article\",\"name\":\"Why Cole Micek Swears By an Extensive Skincare Routine\",\"headline\":\"\\u0e19\\u0e35\\u0e48\\u0e04\\u0e37\\u0e2d\\u0e27\\u0e34\\u0e18\\u0e35\\u0e17\\u0e35\\u0e48 Cole Micek \\u0e40\\u0e15\\u0e23\\u0e35\\u0e22\\u0e21\\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e01\\u0e25\\u0e49\\u0e2d\\u0e07\\u0e40\\u0e2a\\u0e21\\u0e2d\\u0e44\\u0e21\\u0e48\\u0e27\\u0e48\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e34\\u0e15\\u0e08\\u0e30\\u0e1e\\u0e32\\u0e40\\u0e02\\u0e32\\u0e44\\u0e1b\\u0e17\\u0e35\\u0e48\\u0e44\\u0e2b\\u0e19\",\"author\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/angelo-dionora\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/P-3.webp\",\"width\":2560,\"height\":1340},\"datePublished\":\"2025-07-07T18:53:55+08:00\",\"dateModified\":\"2026-03-27T22:58:44+08:00\",\"inLanguage\":\"th\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#webpage\"},\"articleSection\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e44\\u0e23\\u0e49\\u0e2a\\u0e32\\u0e23\\u0e30, Cole Micek, \\u0e04\\u0e27\\u0e32\\u0e21\\u0e44\\u0e23\\u0e49\\u0e2a\\u0e32\\u0e23\\u0e30, \\u0e44\\u0e21\\u0e48\\u0e08\\u0e33\\u0e40\\u0e1b\\u0e47\\u0e19, angelo.dionora\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/#listItem\",\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e44\\u0e23\\u0e49\\u0e2a\\u0e32\\u0e23\\u0e30\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/#listItem\",\"position\":2,\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e44\\u0e23\\u0e49\\u0e2a\\u0e32\\u0e23\\u0e30\",\"item\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#listItem\",\"name\":\"\\u0e19\\u0e35\\u0e48\\u0e04\\u0e37\\u0e2d\\u0e27\\u0e34\\u0e18\\u0e35\\u0e17\\u0e35\\u0e48 Cole Micek \\u0e40\\u0e15\\u0e23\\u0e35\\u0e22\\u0e21\\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e01\\u0e25\\u0e49\\u0e2d\\u0e07\\u0e40\\u0e2a\\u0e21\\u0e2d\\u0e44\\u0e21\\u0e48\\u0e27\\u0e48\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e34\\u0e15\\u0e08\\u0e30\\u0e1e\\u0e32\\u0e40\\u0e02\\u0e32\\u0e44\\u0e1b\\u0e17\\u0e35\\u0e48\\u0e44\\u0e2b\\u0e19\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#listItem\",\"position\":3,\"name\":\"\\u0e19\\u0e35\\u0e48\\u0e04\\u0e37\\u0e2d\\u0e27\\u0e34\\u0e18\\u0e35\\u0e17\\u0e35\\u0e48 Cole Micek \\u0e40\\u0e15\\u0e23\\u0e35\\u0e22\\u0e21\\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e01\\u0e25\\u0e49\\u0e2d\\u0e07\\u0e40\\u0e2a\\u0e21\\u0e2d\\u0e44\\u0e21\\u0e48\\u0e27\\u0e48\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e34\\u0e15\\u0e08\\u0e30\\u0e1e\\u0e32\\u0e40\\u0e02\\u0e32\\u0e44\\u0e1b\\u0e17\\u0e35\\u0e48\\u0e44\\u0e2b\\u0e19\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/category\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/#listItem\",\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e44\\u0e23\\u0e49\\u0e2a\\u0e32\\u0e23\\u0e30\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#organization\",\"name\":\"VMAN SEA\",\"description\":\"The vanguard of men's fashion destinations\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/VMAN_SEA_logo_.png\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#organizationLogo\",\"width\":2560,\"height\":1440,\"caption\":\"VMAN SEA logo\"},\"image\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vmansea\",\"https:\\\/\\\/x.com\\\/vmansea\",\"https:\\\/\\\/www.instagram.com\\\/vmansea\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@vmansea\",\"https:\\\/\\\/www.youtube.com\\\/@vmansea\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/angelo-dionora\\\/#author\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/angelo-dionora\\\/\",\"name\":\"Angelo Dionora\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dd335e856f79f851156a720d41f92390d0d20c40643d9943352750eaa1bed54?s=96&d=mm&r=g\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#webpage\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/\",\"name\":\"Why Cole Micek Swears By an Extensive Skincare Routine\",\"description\":\"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here's how he takes care of himself to face the day.\",\"inLanguage\":\"th\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/angelo-dionora\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/author\\\/angelo-dionora\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/assets.vman-sea.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/P-3.webp\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#mainImage\",\"width\":2560,\"height\":1340},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\\\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\\\/#mainImage\"},\"datePublished\":\"2025-07-07T18:53:55+08:00\",\"dateModified\":\"2026-03-27T22:58:44+08:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/\",\"name\":\"VMAN SEA\",\"description\":\"The vanguard of men's fashion destinations\",\"inLanguage\":\"th\",\"publisher\":{\"@id\":\"https:\\\/\\\/vman-sea.com\\\/th\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Why Cole Micek Swears By an Extensive Skincare Routine<\/title>\n\n","aioseo_head_json":{"title":"Why Cole Micek Swears By an Extensive Skincare Routine","description":"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here's how he takes care of himself to face the day.","canonical_url":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"9sEmVT39iIbCpwNX21rMqd023btuUwORxEIHZ6boG70","msvalidate.01":"3ADFD7977E99135C6276B3B510E26B54","p:domain_verify":"ddd94e5e18aa32daa2fd6fb7f0d982d6","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#article","name":"Why Cole Micek Swears By an Extensive Skincare Routine","headline":"\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 Cole Micek \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19","author":{"@id":"https:\/\/vman-sea.com\/th\/author\/angelo-dionora\/#author"},"publisher":{"@id":"https:\/\/vman-sea.com\/th\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp","width":2560,"height":1340},"datePublished":"2025-07-07T18:53:55+08:00","dateModified":"2026-03-27T22:58:44+08:00","inLanguage":"th","mainEntityOfPage":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#webpage"},"isPartOf":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#webpage"},"articleSection":"\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30, Cole Micek, \u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30, \u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19, angelo.dionora"},{"@type":"BreadcrumbList","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/#listItem","position":1,"name":"Home","item":"https:\/\/vman-sea.com\/th\/","nextItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/#listItem","name":"\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30"}},{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/#listItem","position":2,"name":"\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30","item":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/","nextItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#listItem","name":"\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 Cole Micek \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19"},"previousItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#listItem","position":3,"name":"\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 Cole Micek \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19","previousItem":{"@type":"ListItem","@id":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/#listItem","name":"\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30"}}]},{"@type":"Organization","@id":"https:\/\/vman-sea.com\/th\/#organization","name":"VMAN SEA","description":"The vanguard of men's fashion destinations","url":"https:\/\/vman-sea.com\/th\/","logo":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2024\/11\/VMAN_SEA_logo_.png","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#organizationLogo","width":2560,"height":1440,"caption":"VMAN SEA logo"},"image":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/vmansea","https:\/\/x.com\/vmansea","https:\/\/www.instagram.com\/vmansea\/","https:\/\/www.tiktok.com\/@vmansea","https:\/\/www.youtube.com\/@vmansea"]},{"@type":"Person","@id":"https:\/\/vman-sea.com\/th\/author\/angelo-dionora\/#author","url":"https:\/\/vman-sea.com\/th\/author\/angelo-dionora\/","name":"Angelo Dionora","image":{"@type":"ImageObject","url":"https:\/\/secure.gravatar.com\/avatar\/7dd335e856f79f851156a720d41f92390d0d20c40643d9943352750eaa1bed54?s=96&d=mm&r=g"}},{"@type":"WebPage","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#webpage","url":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/","name":"Why Cole Micek Swears By an Extensive Skincare Routine","description":"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here's how he takes care of himself to face the day.","inLanguage":"th","isPartOf":{"@id":"https:\/\/vman-sea.com\/th\/#website"},"breadcrumb":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#breadcrumblist"},"author":{"@id":"https:\/\/vman-sea.com\/th\/author\/angelo-dionora\/#author"},"creator":{"@id":"https:\/\/vman-sea.com\/th\/author\/angelo-dionora\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp","@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#mainImage","width":2560,"height":1340},"primaryImageOfPage":{"@id":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/#mainImage"},"datePublished":"2025-07-07T18:53:55+08:00","dateModified":"2026-03-27T22:58:44+08:00"},{"@type":"WebSite","@id":"https:\/\/vman-sea.com\/th\/#website","url":"https:\/\/vman-sea.com\/th\/","name":"VMAN SEA","description":"The vanguard of men's fashion destinations","inLanguage":"th","publisher":{"@id":"https:\/\/vman-sea.com\/th\/#organization"}}]},"og:locale":"th_TH","og:site_name":"VMAN SEA | The vanguard of men's fashion destinations","og:type":"article","og:title":"Why Cole Micek Swears By an Extensive Skincare Routine","og:description":"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here's how he takes care of himself to face the day.","og:url":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/","og:image":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp","og:image:secure_url":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp","og:image:width":2560,"og:image:height":1340,"article:published_time":"2025-07-07T10:53:55+00:00","article:modified_time":"2026-03-27T14:58:44+00:00","twitter:card":"summary_large_image","twitter:title":"Why Cole Micek Swears By an Extensive Skincare Routine","twitter:description":"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here's how he takes care of himself to face the day.","twitter:image":"https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp","twitter:label1":"Written by","twitter:data1":"Angelo Dionora"},"aioseo_meta_data":{"post_id":"26906","title":"Why Cole Micek Swears By an Extensive Skincare Routine","description":"Filipino-American model, actor, and athlete Cole Micek works hard on the court and in front of the camera. Here's how he takes care of himself to face the day.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Cole Micek","score":75,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"routine","score":83,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},{"keyphrase":"Skincare","score":58,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:26:57","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-07-07 10:54:16","updated":"2026-05-15 10:26:57"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/vman-sea.com\/th\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/vman-sea.com\/th\/category\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/\" title=\"\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30\">\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 Cole Micek \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/vman-sea.com\/th\/"},{"label":"\u0e04\u0e27\u0e32\u0e21\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30","link":"https:\/\/vman-sea.com\/th\/category\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/"},{"label":"\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 Cole Micek \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19","link":"https:\/\/vman-sea.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%84%e0%b8%a3%e0%b9%89%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%b0\/%e0%b8%99%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%b7%e0%b8%ad%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88-cole-micek-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%9e\/"}],"uagb_featured_image_src":{"full":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",2560,1340,false],"thumbnail":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",128,67,false],"medium":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",2560,1340,false],"medium_large":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",640,335,false],"large":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",2560,1340,false],"1536x1536":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",1536,804,false],"2048x2048":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",2048,1072,false],"120w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-120x120.webp",120,120,true],"240w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-240x240.webp",240,240,true],"320w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-320x320.webp",320,320,true],"640w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-640x640.webp",640,640,true],"960w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-960x960.webp",960,960,true],"1280w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-1280x1280.webp",1280,1280,true],"1600w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-1600x1340.webp",1600,1340,true],"1920w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-1920x1340.webp",1920,1340,true],"2240w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-2240x1340.webp",2240,1340,true],"2560w_square":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",2560,1340,false],"120w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-120x63.webp",120,63,true],"240w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-240x126.webp",240,126,true],"320w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-320x168.webp",320,168,true],"640w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-640x335.webp",640,335,true],"960w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-960x503.webp",960,503,true],"1280w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-1280x670.webp",1280,670,true],"1600w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-1600x838.webp",1600,838,true],"1920w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-1920x1005.webp",1920,1005,true],"2240w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3-2240x1173.webp",2240,1173,true],"2560w":["https:\/\/assets.vman-sea.com\/wp-content\/uploads\/2025\/07\/P-3.webp",2560,1340,false]},"uagb_author_info":{"display_name":"Angelo Dionora","author_link":"https:\/\/vman-sea.com\/th\/author\/angelo-dionora\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e17\u0e38\u0e01\u0e01\u0e49\u0e32\u0e27\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22 \u201c\u0e1c\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49&hellip;","_links":{"self":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/posts\/26906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/comments?post=26906"}],"version-history":[{"count":0,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/posts\/26906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/media\/26858"}],"wp:attachment":[{"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/media?parent=26906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/categories?post=26906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/tags?post=26906"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/vman-sea.com\/th\/wp-json\/wp\/v2\/coauthors?post=26906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}